{"id":19788,"date":"2022-10-19T01:28:19","date_gmt":"2022-10-18T23:28:19","guid":{"rendered":"http:\/\/dev.editorialclaret.cat\/autor\/patxi-martinez-zabalo\/"},"modified":"2022-10-19T01:28:19","modified_gmt":"2022-10-18T23:28:19","slug":"patxi-martinez-zabalo","status":"publish","type":"autor","link":"https:\/\/www.editorialclaret.cat\/es\/autor\/patxi-martinez-zabalo\/","title":{"rendered":"PATXI &#8211; MARTINEZ ZABALO"},"content":{"rendered":"","protected":false},"featured_media":0,"template":"","meta":{"_acf_changed":false,"rs_blank_template":"","rs_page_bg_color":"","slide_template_v7":"","inline_featured_image":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0},"class_list":["post-19788","autor","type-autor","status-publish","hentry"],"acf":{"nombre":null,"apellido":null,"bio_esp":null,"libros":null},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Editorial Claret<\/title>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"PATXI - MARTINEZ ZABALO - Editorial Claret\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.editorialclaret.cat\/autor\/patxi-martinez-zabalo\/\" \/>\n<meta property=\"og:site_name\" content=\"Editorial Claret\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.editorialclaret.cat\\\/autor\\\/patxi-martinez-zabalo\\\/\",\"url\":\"https:\\\/\\\/www.editorialclaret.cat\\\/autor\\\/patxi-martinez-zabalo\\\/\",\"name\":\"PATXI - MARTINEZ ZABALO - Editorial Claret\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.editorialclaret.cat\\\/#website\"},\"datePublished\":\"2022-10-18T23:28:19+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.editorialclaret.cat\\\/autor\\\/patxi-martinez-zabalo\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.editorialclaret.cat\\\/autor\\\/patxi-martinez-zabalo\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.editorialclaret.cat\\\/autor\\\/patxi-martinez-zabalo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.editorialclaret.cat\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Autores\",\"item\":\"https:\\\/\\\/www.editorialclaret.cat\\\/autor\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"PATXI &#8211; MARTINEZ ZABALO\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.editorialclaret.cat\\\/#website\",\"url\":\"https:\\\/\\\/www.editorialclaret.cat\\\/\",\"name\":\"Editorial Claret\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.editorialclaret.cat\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.editorialclaret.cat\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.editorialclaret.cat\\\/#organization\",\"name\":\"Editorial Claret\",\"url\":\"https:\\\/\\\/www.editorialclaret.cat\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.editorialclaret.cat\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.editorialclaret.cat\\\/wp-content\\\/uploads\\\/.\\\/logo-claret.png\",\"contentUrl\":\"https:\\\/\\\/www.editorialclaret.cat\\\/wp-content\\\/uploads\\\/.\\\/logo-claret.png\",\"width\":194,\"height\":79,\"caption\":\"Editorial Claret\"},\"image\":{\"@id\":\"https:\\\/\\\/www.editorialclaret.cat\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Editorial Claret","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"es_ES","og_type":"article","og_title":"PATXI - MARTINEZ ZABALO - Editorial Claret","og_url":"https:\/\/www.editorialclaret.cat\/autor\/patxi-martinez-zabalo\/","og_site_name":"Editorial Claret","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.editorialclaret.cat\/autor\/patxi-martinez-zabalo\/","url":"https:\/\/www.editorialclaret.cat\/autor\/patxi-martinez-zabalo\/","name":"PATXI - MARTINEZ ZABALO - Editorial Claret","isPartOf":{"@id":"https:\/\/www.editorialclaret.cat\/#website"},"datePublished":"2022-10-18T23:28:19+00:00","breadcrumb":{"@id":"https:\/\/www.editorialclaret.cat\/autor\/patxi-martinez-zabalo\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.editorialclaret.cat\/autor\/patxi-martinez-zabalo\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.editorialclaret.cat\/autor\/patxi-martinez-zabalo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.editorialclaret.cat\/es\/"},{"@type":"ListItem","position":2,"name":"Autores","item":"https:\/\/www.editorialclaret.cat\/autor\/"},{"@type":"ListItem","position":3,"name":"PATXI &#8211; MARTINEZ ZABALO"}]},{"@type":"WebSite","@id":"https:\/\/www.editorialclaret.cat\/#website","url":"https:\/\/www.editorialclaret.cat\/","name":"Editorial Claret","description":"","publisher":{"@id":"https:\/\/www.editorialclaret.cat\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.editorialclaret.cat\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.editorialclaret.cat\/#organization","name":"Editorial Claret","url":"https:\/\/www.editorialclaret.cat\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.editorialclaret.cat\/#\/schema\/logo\/image\/","url":"https:\/\/www.editorialclaret.cat\/wp-content\/uploads\/.\/logo-claret.png","contentUrl":"https:\/\/www.editorialclaret.cat\/wp-content\/uploads\/.\/logo-claret.png","width":194,"height":79,"caption":"Editorial Claret"},"image":{"@id":"https:\/\/www.editorialclaret.cat\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.editorialclaret.cat\/es\/wp-json\/wp\/v2\/autor\/19788","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.editorialclaret.cat\/es\/wp-json\/wp\/v2\/autor"}],"about":[{"href":"https:\/\/www.editorialclaret.cat\/es\/wp-json\/wp\/v2\/types\/autor"}],"wp:attachment":[{"href":"https:\/\/www.editorialclaret.cat\/es\/wp-json\/wp\/v2\/media?parent=19788"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}